{"id":8060,"date":"2019-04-29T11:02:38","date_gmt":"2019-04-29T11:02:38","guid":{"rendered":"https:\/\/www.jobup.ch\/?p=8060"},"modified":"2019-04-29T11:02:38","modified_gmt":"2019-04-29T11:02:38","slug":"quelles-sont-les-differentes-retenues-sur-le-salaire","status":"publish","type":"post","link":"https:\/\/www.jobup.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/","title":{"rendered":"Quelles sont les diff\u00e9rentes retenues sur le salaire?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":8222,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[104,262,774,775],"class_list":["post-8060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salaire-avantages","tag-assurances-sociales","tag-deductions","tag-retenues","tag-retenues-salariales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse<\/title>\n<meta name=\"description\" content=\"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse\" \/>\n<meta property=\"og:description\" content=\"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T11:02:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Auteur invit\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Auteur invit\u00e9\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/\"},\"author\":{\"name\":\"Auteur invit\u00e9\",\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/#\\\/schema\\\/person\\\/2c9536a23fd6195f1fd7cb2247f8807a\"},\"headline\":\"Quelles sont les diff\u00e9rentes retenues sur le salaire?\",\"datePublished\":\"2019-04-29T11:02:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/\"},\"wordCount\":9,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lohnabrechnung_ch.jpeg\",\"keywords\":[\"assurances sociales\",\"d\u00e9ductions\",\"retenues\",\"retenues salariales\"],\"articleSection\":[\"Salaire | Avantages\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/\",\"url\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/\",\"name\":\"Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lohnabrechnung_ch.jpeg\",\"datePublished\":\"2019-04-29T11:02:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/#\\\/schema\\\/person\\\/2c9536a23fd6195f1fd7cb2247f8807a\"},\"description\":\"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lohnabrechnung_ch.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lohnabrechnung_ch.jpeg\",\"width\":950,\"height\":420,\"caption\":\"retenues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jobs.ch\\\/fr\\\/job-coach\\\/quelles-sont-les-differentes-retenues-sur-le-salaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelles sont les diff\u00e9rentes retenues sur le salaire?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/#website\",\"url\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/\",\"name\":\"Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse\",\"description\":\"jobup.ch Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/#\\\/schema\\\/person\\\/2c9536a23fd6195f1fd7cb2247f8807a\",\"name\":\"Auteur invit\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g\",\"caption\":\"Auteur invit\u00e9\"},\"description\":\"R\u00e9guli\u00e8rement, nous invitons diff\u00e9rents auteurs et sp\u00e9cialistes afin de venir parler d'un sujet en particulier et pour vous donner des conseils avis\u00e9s sur la recherche d'emploi.\",\"url\":\"https:\\\/\\\/www.jobup.ch\\\/fr\\\/job-coach\\\/author\\\/auteur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse","description":"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse","og_description":"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.","og_url":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/","og_site_name":"Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse","article_published_time":"2019-04-29T11:02:38+00:00","og_image":[{"width":950,"height":420,"url":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg","type":"image\/jpeg"}],"author":"Auteur invit\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Auteur invit\u00e9"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#article","isPartOf":{"@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/"},"author":{"name":"Auteur invit\u00e9","@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/#\/schema\/person\/2c9536a23fd6195f1fd7cb2247f8807a"},"headline":"Quelles sont les diff\u00e9rentes retenues sur le salaire?","datePublished":"2019-04-29T11:02:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/"},"wordCount":9,"commentCount":0,"image":{"@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg","keywords":["assurances sociales","d\u00e9ductions","retenues","retenues salariales"],"articleSection":["Salaire | Avantages"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/","url":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/","name":"Quelles sont les diff\u00e9rentes retenues sur le salaire? - Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse","isPartOf":{"@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#primaryimage"},"image":{"@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg","datePublished":"2019-04-29T11:02:38+00:00","author":{"@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/#\/schema\/person\/2c9536a23fd6195f1fd7cb2247f8807a"},"description":"De nombreux jeunes sont surpris du montant pr\u00e9lev\u00e9 sur leur salaire pour les assurances sociales. Petit aper\u00e7u des diff\u00e9rentes d\u00e9ductions.","breadcrumb":{"@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#primaryimage","url":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg","contentUrl":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-content\/uploads\/2019\/04\/lohnabrechnung_ch.jpeg","width":950,"height":420,"caption":"retenues"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jobs.ch\/fr\/job-coach\/quelles-sont-les-differentes-retenues-sur-le-salaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jobup.ch\/fr\/job-coach\/"},{"@type":"ListItem","position":2,"name":"Quelles sont les diff\u00e9rentes retenues sur le salaire?"}]},{"@type":"WebSite","@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/#website","url":"https:\/\/www.jobup.ch\/fr\/job-coach\/","name":"Bienvenue sur le Job Coach, le guide consacr\u00e9 \u00e0 la recherche d\u2019emploi en Suisse","description":"jobup.ch Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jobup.ch\/fr\/job-coach\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.jobup.ch\/fr\/job-coach\/#\/schema\/person\/2c9536a23fd6195f1fd7cb2247f8807a","name":"Auteur invit\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9dc1faae53ffa6f9b3ca06fdad26309ad01385c723a405d5f9114d4bdb2c4e1?s=96&d=mm&r=g","caption":"Auteur invit\u00e9"},"description":"R\u00e9guli\u00e8rement, nous invitons diff\u00e9rents auteurs et sp\u00e9cialistes afin de venir parler d'un sujet en particulier et pour vous donner des conseils avis\u00e9s sur la recherche d'emploi.","url":"https:\/\/www.jobup.ch\/fr\/job-coach\/author\/auteur\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/posts\/8060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/comments?post=8060"}],"version-history":[{"count":0,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/posts\/8060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/media\/8222"}],"wp:attachment":[{"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/media?parent=8060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/categories?post=8060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobup.ch\/fr\/job-coach\/wp-json\/wp\/v2\/tags?post=8060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}